{"id":3,"count":20,"description":"","link":"http:\/\/sekaishinbun.net\/travellers-check\/category\/a-to-z\/","name":"\u30c8\u30e9\u30d9\u30e9\u30fc\u30ba\u30c1\u30a7\u30c3\u30afAtoZ","slug":"a-to-z","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/sekaishinbun.net\/travellers-check\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sekaishinbun.net\/travellers-check\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/sekaishinbun.net\/travellers-check\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/sekaishinbun.net\/travellers-check\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}